{"id":490,"date":"2012-11-21T12:15:22","date_gmt":"2012-11-21T10:15:22","guid":{"rendered":"https:\/\/www.funiculart.fr\/ressources\/?p=490"},"modified":"2013-01-29T14:19:27","modified_gmt":"2013-01-29T12:19:27","slug":"tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme","status":"publish","type":"post","link":"https:\/\/www.funiculart.fr\/ressources\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\/","title":{"rendered":"Tribunal de commerce de Saint Valery : En images l&rsquo;expo \u00ab\u00a0Territoire Baie de Somme\u00a0\u00bb !"},"content":{"rendered":"<p>C&rsquo;est la deuxi\u00e8me \u00e9dition de l&rsquo;expo <strong>\u00ab\u00a0Territoire Baie de Somme\u00a0\u00bb<\/strong> qui s&rsquo;est tenue en ce d\u00e9but novembre 2012. Cette assembl\u00e9e r\u00e9unie les savoir-faire artistiques de la Baie de Somme au Tribunal de Commerce (reconverti d\u00e9finitivement en lieu culturel) \u00e0 Saint-Valery en Picardie.<\/p>\n<p>Tous les artistes professionnels rassembl\u00e9s au sein de cette expo associative n&rsquo;ont qu&rsquo;un seul mot d&rsquo;ordre : la bonne humeur ! Le ton f\u00fbt donn\u00e9 dans cette magnifique salle lumineuse et <a href=\"https:\/\/www.funiculart.fr\/ressources\/tribunal-de-commerce-de-saint-valery\/\">Funiculart vous propose aujourd&rsquo;hui de d\u00e9couvrir en image cette exposition <strong>\u00ab\u00a0Territoire Baie de Somme\u00a0\u00bb<\/strong>. <\/a><\/p>\n<p>Le Tribunal de Commerce chapeaut\u00e9 par St\u00e9phane Haussoulier et son \u00e9quipe rencontre un franc succ\u00e8s aux yeux du public et des artistes qui y exposent. Funiculart vous recommande ce lieu !<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-492\" title=\"DSC03506u\" alt=\"\" src=\"https:\/\/www.funiculart.fr\/ressources\/wp-content\/uploads\/2012\/11\/DSC03506u.jpg\" width=\"500\" height=\"153\" \/><\/p>\n<blockquote><p>A noter : Envoyez-nous vous aussi les images de vos expositions pass\u00e9es, afin de faire d\u00e9couvrir aux autres artistes des lieux dignes de ce nom dans notre belle r\u00e9gion !\u00a0\u00a0<a href=\"mailto:funiculart@gmail.com\"> &gt;&gt;&gt;contact<\/a><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est la deuxi\u00e8me \u00e9dition de l&rsquo;expo \u00ab\u00a0Territoire Baie de Somme\u00a0\u00bb qui s&rsquo;est tenue en ce d\u00e9but novembre 2012. Cette assembl\u00e9e r\u00e9unie les savoir-faire artistiques de la Baie de Somme au Tribunal de Commerce (reconverti d\u00e9finitivement en lieu culturel) \u00e0 Saint-Valery en Picardie. Tous les artistes professionnels rassembl\u00e9s au sein de cette expo associative n&rsquo;ont qu&rsquo;un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-490","post","type-post","status-publish","format-standard","hentry","category-sur-funiculart"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"C&#039;est la deuxi\u00e8me \u00e9dition de l&#039;expo &quot;Territoire Baie de Somme&quot; qui s&#039;est tenue en ce d\u00e9but novembre 2012. Cette assembl\u00e9e r\u00e9unie les savoir-faire artistiques de la Baie de Somme au Tribunal de Commerce (reconverti d\u00e9finitivement en lieu culturel) \u00e0 Saint-Valery en Picardie. Tous les artistes professionnels rassembl\u00e9s au sein de cette expo associative n&#039;ont qu&#039;un\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"jean-marc\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.funiculart.fr\/ressources\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Funiculart \u2013 Ressources pour artistes du Nord Pas-de-Calais et Picardie\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Tribunal de commerce de Saint Valery : En images l\u2019expo \u00ab Territoire Baie de Somme \u00bb ! | Funiculart\" \/>\n\t\t<meta property=\"og:description\" content=\"C&#039;est la deuxi\u00e8me \u00e9dition de l&#039;expo &quot;Territoire Baie de Somme&quot; qui s&#039;est tenue en ce d\u00e9but novembre 2012. Cette assembl\u00e9e r\u00e9unie les savoir-faire artistiques de la Baie de Somme au Tribunal de Commerce (reconverti d\u00e9finitivement en lieu culturel) \u00e0 Saint-Valery en Picardie. Tous les artistes professionnels rassembl\u00e9s au sein de cette expo associative n&#039;ont qu&#039;un\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.funiculart.fr\/ressources\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2012-11-21T10:15:22+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2013-01-29T12:19:27+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Tribunal de commerce de Saint Valery : En images l\u2019expo \u00ab Territoire Baie de Somme \u00bb ! | Funiculart\" \/>\n\t\t<meta name=\"twitter:description\" content=\"C&#039;est la deuxi\u00e8me \u00e9dition de l&#039;expo &quot;Territoire Baie de Somme&quot; qui s&#039;est tenue en ce d\u00e9but novembre 2012. Cette assembl\u00e9e r\u00e9unie les savoir-faire artistiques de la Baie de Somme au Tribunal de Commerce (reconverti d\u00e9finitivement en lieu culturel) \u00e0 Saint-Valery en Picardie. Tous les artistes professionnels rassembl\u00e9s au sein de cette expo associative n&#039;ont qu&#039;un\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\\\/#article\",\"name\":\"Tribunal de commerce de Saint Valery : En images l\\u2019expo \\u00ab Territoire Baie de Somme \\u00bb ! | Funiculart\",\"headline\":\"Tribunal de commerce de Saint Valery : En images l&rsquo;expo \\u00ab\\u00a0Territoire Baie de Somme\\u00a0\\u00bb !\",\"author\":{\"@id\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/author\\\/jean-marc\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/wp-content\\\/uploads\\\/2012\\\/11\\\/DSC03506u.jpg\",\"@id\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\\\/#articleImage\",\"width\":500,\"height\":153},\"datePublished\":\"2012-11-21T12:15:22+02:00\",\"dateModified\":\"2013-01-29T14:19:27+02:00\",\"inLanguage\":\"fr-FR\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\\\/#webpage\"},\"articleSection\":\"Funiculart\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/category\\\/sur-funiculart\\\/#listItem\",\"name\":\"Funiculart\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/category\\\/sur-funiculart\\\/#listItem\",\"position\":2,\"name\":\"Funiculart\",\"item\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/category\\\/sur-funiculart\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\\\/#listItem\",\"name\":\"Tribunal de commerce de Saint Valery : En images l&rsquo;expo \\u00ab\\u00a0Territoire Baie de Somme\\u00a0\\u00bb !\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\\\/#listItem\",\"position\":3,\"name\":\"Tribunal de commerce de Saint Valery : En images l&rsquo;expo \\u00ab\\u00a0Territoire Baie de Somme\\u00a0\\u00bb !\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/category\\\/sur-funiculart\\\/#listItem\",\"name\":\"Funiculart\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/#organization\",\"name\":\"Jean-Marc Denecker\",\"description\":\"Ressources pour artistes du Nord Pas-de-Calais et Picardie\",\"url\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/funiculart.png\",\"@id\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\\\/#organizationLogo\",\"width\":112,\"height\":112},\"image\":{\"@id\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/author\\\/jean-marc\\\/#author\",\"url\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/author\\\/jean-marc\\\/\",\"name\":\"jean-marc\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\\\/#webpage\",\"url\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\\\/\",\"name\":\"Tribunal de commerce de Saint Valery : En images l\\u2019expo \\u00ab Territoire Baie de Somme \\u00bb ! | Funiculart\",\"description\":\"C'est la deuxi\\u00e8me \\u00e9dition de l'expo \\\"Territoire Baie de Somme\\\" qui s'est tenue en ce d\\u00e9but novembre 2012. Cette assembl\\u00e9e r\\u00e9unie les savoir-faire artistiques de la Baie de Somme au Tribunal de Commerce (reconverti d\\u00e9finitivement en lieu culturel) \\u00e0 Saint-Valery en Picardie. Tous les artistes professionnels rassembl\\u00e9s au sein de cette expo associative n'ont qu'un\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/author\\\/jean-marc\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/author\\\/jean-marc\\\/#author\"},\"datePublished\":\"2012-11-21T12:15:22+02:00\",\"dateModified\":\"2013-01-29T14:19:27+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/#website\",\"url\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/\",\"name\":\"Funiculart : Cours de dessins, sculpture, expositions\",\"alternateName\":\"Ressources pour artistes\",\"description\":\"Ressources pour artistes du Nord Pas-de-Calais et Picardie\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.funiculart.fr\\\/ressources\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Tribunal de commerce de Saint Valery : En images l\u2019expo \u00ab Territoire Baie de Somme \u00bb ! | Funiculart","description":"C'est la deuxi\u00e8me \u00e9dition de l'expo \"Territoire Baie de Somme\" qui s'est tenue en ce d\u00e9but novembre 2012. Cette assembl\u00e9e r\u00e9unie les savoir-faire artistiques de la Baie de Somme au Tribunal de Commerce (reconverti d\u00e9finitivement en lieu culturel) \u00e0 Saint-Valery en Picardie. Tous les artistes professionnels rassembl\u00e9s au sein de cette expo associative n'ont qu'un","canonical_url":"https:\/\/www.funiculart.fr\/ressources\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.funiculart.fr\/ressources\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\/#article","name":"Tribunal de commerce de Saint Valery : En images l\u2019expo \u00ab Territoire Baie de Somme \u00bb ! | Funiculart","headline":"Tribunal de commerce de Saint Valery : En images l&rsquo;expo \u00ab\u00a0Territoire Baie de Somme\u00a0\u00bb !","author":{"@id":"https:\/\/www.funiculart.fr\/ressources\/author\/jean-marc\/#author"},"publisher":{"@id":"https:\/\/www.funiculart.fr\/ressources\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.funiculart.fr\/ressources\/wp-content\/uploads\/2012\/11\/DSC03506u.jpg","@id":"https:\/\/www.funiculart.fr\/ressources\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\/#articleImage","width":500,"height":153},"datePublished":"2012-11-21T12:15:22+02:00","dateModified":"2013-01-29T14:19:27+02:00","inLanguage":"fr-FR","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/www.funiculart.fr\/ressources\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\/#webpage"},"isPartOf":{"@id":"https:\/\/www.funiculart.fr\/ressources\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\/#webpage"},"articleSection":"Funiculart"},{"@type":"BreadcrumbList","@id":"https:\/\/www.funiculart.fr\/ressources\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.funiculart.fr\/ressources#listItem","position":1,"name":"Home","item":"https:\/\/www.funiculart.fr\/ressources","nextItem":{"@type":"ListItem","@id":"https:\/\/www.funiculart.fr\/ressources\/category\/sur-funiculart\/#listItem","name":"Funiculart"}},{"@type":"ListItem","@id":"https:\/\/www.funiculart.fr\/ressources\/category\/sur-funiculart\/#listItem","position":2,"name":"Funiculart","item":"https:\/\/www.funiculart.fr\/ressources\/category\/sur-funiculart\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.funiculart.fr\/ressources\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\/#listItem","name":"Tribunal de commerce de Saint Valery : En images l&rsquo;expo \u00ab\u00a0Territoire Baie de Somme\u00a0\u00bb !"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.funiculart.fr\/ressources#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.funiculart.fr\/ressources\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\/#listItem","position":3,"name":"Tribunal de commerce de Saint Valery : En images l&rsquo;expo \u00ab\u00a0Territoire Baie de Somme\u00a0\u00bb !","previousItem":{"@type":"ListItem","@id":"https:\/\/www.funiculart.fr\/ressources\/category\/sur-funiculart\/#listItem","name":"Funiculart"}}]},{"@type":"Organization","@id":"https:\/\/www.funiculart.fr\/ressources\/#organization","name":"Jean-Marc Denecker","description":"Ressources pour artistes du Nord Pas-de-Calais et Picardie","url":"https:\/\/www.funiculart.fr\/ressources\/","logo":{"@type":"ImageObject","url":"https:\/\/www.funiculart.fr\/ressources\/wp-content\/uploads\/2022\/11\/funiculart.png","@id":"https:\/\/www.funiculart.fr\/ressources\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\/#organizationLogo","width":112,"height":112},"image":{"@id":"https:\/\/www.funiculart.fr\/ressources\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.funiculart.fr\/ressources\/author\/jean-marc\/#author","url":"https:\/\/www.funiculart.fr\/ressources\/author\/jean-marc\/","name":"jean-marc"},{"@type":"WebPage","@id":"https:\/\/www.funiculart.fr\/ressources\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\/#webpage","url":"https:\/\/www.funiculart.fr\/ressources\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\/","name":"Tribunal de commerce de Saint Valery : En images l\u2019expo \u00ab Territoire Baie de Somme \u00bb ! | Funiculart","description":"C'est la deuxi\u00e8me \u00e9dition de l'expo \"Territoire Baie de Somme\" qui s'est tenue en ce d\u00e9but novembre 2012. Cette assembl\u00e9e r\u00e9unie les savoir-faire artistiques de la Baie de Somme au Tribunal de Commerce (reconverti d\u00e9finitivement en lieu culturel) \u00e0 Saint-Valery en Picardie. Tous les artistes professionnels rassembl\u00e9s au sein de cette expo associative n'ont qu'un","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/www.funiculart.fr\/ressources\/#website"},"breadcrumb":{"@id":"https:\/\/www.funiculart.fr\/ressources\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\/#breadcrumblist"},"author":{"@id":"https:\/\/www.funiculart.fr\/ressources\/author\/jean-marc\/#author"},"creator":{"@id":"https:\/\/www.funiculart.fr\/ressources\/author\/jean-marc\/#author"},"datePublished":"2012-11-21T12:15:22+02:00","dateModified":"2013-01-29T14:19:27+02:00"},{"@type":"WebSite","@id":"https:\/\/www.funiculart.fr\/ressources\/#website","url":"https:\/\/www.funiculart.fr\/ressources\/","name":"Funiculart : Cours de dessins, sculpture, expositions","alternateName":"Ressources pour artistes","description":"Ressources pour artistes du Nord Pas-de-Calais et Picardie","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/www.funiculart.fr\/ressources\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Funiculart \u2013 Ressources pour artistes du Nord Pas-de-Calais et Picardie","og:type":"article","og:title":"Tribunal de commerce de Saint Valery : En images l\u2019expo \u00ab Territoire Baie de Somme \u00bb ! | Funiculart","og:description":"C'est la deuxi\u00e8me \u00e9dition de l'expo &quot;Territoire Baie de Somme&quot; qui s'est tenue en ce d\u00e9but novembre 2012. Cette assembl\u00e9e r\u00e9unie les savoir-faire artistiques de la Baie de Somme au Tribunal de Commerce (reconverti d\u00e9finitivement en lieu culturel) \u00e0 Saint-Valery en Picardie. Tous les artistes professionnels rassembl\u00e9s au sein de cette expo associative n'ont qu'un","og:url":"https:\/\/www.funiculart.fr\/ressources\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\/","article:published_time":"2012-11-21T10:15:22+00:00","article:modified_time":"2013-01-29T12:19:27+00:00","twitter:card":"summary","twitter:title":"Tribunal de commerce de Saint Valery : En images l\u2019expo \u00ab Territoire Baie de Somme \u00bb ! | Funiculart","twitter:description":"C'est la deuxi\u00e8me \u00e9dition de l'expo &quot;Territoire Baie de Somme&quot; qui s'est tenue en ce d\u00e9but novembre 2012. Cette assembl\u00e9e r\u00e9unie les savoir-faire artistiques de la Baie de Somme au Tribunal de Commerce (reconverti d\u00e9finitivement en lieu culturel) \u00e0 Saint-Valery en Picardie. Tous les artistes professionnels rassembl\u00e9s au sein de cette expo associative n'ont qu'un"},"aioseo_meta_data":{"post_id":"490","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-18 12:26:42","updated":"2025-06-04 01:23:54","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.funiculart.fr\/ressources\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.funiculart.fr\/ressources\/category\/sur-funiculart\/\" title=\"Funiculart\">Funiculart<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tTribunal de commerce de Saint Valery : En images l\u2019expo \u00ab Territoire Baie de Somme \u00bb !\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.funiculart.fr\/ressources"},{"label":"Funiculart","link":"https:\/\/www.funiculart.fr\/ressources\/category\/sur-funiculart\/"},{"label":"Tribunal de commerce de Saint Valery : En images l&rsquo;expo \u00ab\u00a0Territoire Baie de Somme\u00a0\u00bb !","link":"https:\/\/www.funiculart.fr\/ressources\/tribunal-de-commerce-de-saint-valery-en-image-lexpo-territoire-baie-desomme\/"}],"_links":{"self":[{"href":"https:\/\/www.funiculart.fr\/ressources\/wp-json\/wp\/v2\/posts\/490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.funiculart.fr\/ressources\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.funiculart.fr\/ressources\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.funiculart.fr\/ressources\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.funiculart.fr\/ressources\/wp-json\/wp\/v2\/comments?post=490"}],"version-history":[{"count":0,"href":"https:\/\/www.funiculart.fr\/ressources\/wp-json\/wp\/v2\/posts\/490\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.funiculart.fr\/ressources\/wp-json\/wp\/v2\/media?parent=490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.funiculart.fr\/ressources\/wp-json\/wp\/v2\/categories?post=490"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.funiculart.fr\/ressources\/wp-json\/wp\/v2\/tags?post=490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}